{"id":1350,"date":"2024-04-17T14:16:20","date_gmt":"2024-04-17T19:16:20","guid":{"rendered":"https:\/\/endeavorct.com\/?p=1350"},"modified":"2026-04-21T15:16:57","modified_gmt":"2026-04-21T20:16:57","slug":"national-minority-health-month","status":"publish","type":"post","link":"https:\/\/endeavorct.com\/es\/national-minority-health-month\/","title":{"rendered":"MES NACIONAL DE LA SALUD DE LAS MINOR\u00cdAS"},"content":{"rendered":"<p>Para celebrar el Mes Nacional de la Salud de las Minor\u00edas, analizamos el impacto de la diversidad en los ensayos cl\u00ednicos sobre la salud p\u00fablica. Los ensayos cl\u00ednicos desempe\u00f1an un papel crucial en la investigaci\u00f3n m\u00e9dica al probar la seguridad y eficacia de nuevos tratamientos, por lo que es esencial que reflejen con precisi\u00f3n la poblaci\u00f3n a la que pretenden servir. Siga leyendo para obtener m\u00e1s informaci\u00f3n sobre este importante tema.<\/p>\n<p>&nbsp;<\/p>\n<p>Concientizaci\u00f3n<\/p>\n<p>El Mes Nacional de la Salud de las Minor\u00edas se estableci\u00f3 con una misi\u00f3n clara: destacar las disparidades en materia de salud entre los grupos minoritarios en los Estados Unidos y trabajar para eliminarlas. La celebraci\u00f3n de este mes es fundamental, ya que promueve la concienciaci\u00f3n sobre los diversos or\u00edgenes, culturas y estilos de vida dentro de las comunidades minoritarias, lo que ayuda a los profesionales m\u00e9dicos a brindar una atenci\u00f3n m\u00e1s personalizada y precisa. La inclusi\u00f3n debe seguir siendo una prioridad a la hora de dar forma a las pr\u00e1cticas m\u00e9dicas para garantizar una representaci\u00f3n y un tratamiento equitativos.<\/p>\n<p>&nbsp;<\/p>\n<p>Enfermedades hep\u00e1ticas y renales en poblaciones minoritarias<\/p>\n<p>M\u00e1s de 100 millones de personas en los EE. UU. padecen enfermedades hep\u00e1ticas, mientras que 37 millones padecen enfermedades renales cr\u00f3nicas. Lamentablemente, los grupos minoritarios enfrentan mayores riesgos. Las investigaciones indican que las poblaciones afroamericanas y latinas tienen tasas desproporcionadamente altas de enfermedades hep\u00e1ticas y renales. Seg\u00fan la Asociaci\u00f3n Estadounidense de Diabetes, los adultos afroamericanos tienen tres veces m\u00e1s probabilidades de sufrir enfermedades renales terminales en comparaci\u00f3n con los estadounidenses blancos. De manera similar, los adultos hispanos tienen un riesgo 1,5 veces mayor de padecer esta afecci\u00f3n grave.<\/p>\n<p>&nbsp;<\/p>\n<p>Otras minor\u00edas tambi\u00e9n enfrentan mayores riesgos, como los estadounidenses de origen asi\u00e1tico con c\u00e1ncer de h\u00edgado y los estadounidenses nativos con cirrosis. Reconocer estas tendencias es crucial para brindar atenci\u00f3n m\u00e9dica de alta calidad que pueda prevenir estas afecciones. Es igualmente importante que las personas de estos grupos minoritarios de alto riesgo controlen regularmente su salud para detectar cualquier signo o s\u00edntoma.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-5677 aligncenter\" src=\"https:\/\/brainmattersresearch.com\/wp-content\/uploads\/2024\/04\/Value-of-Representation-in-Clincial-Trials-300x158.jpg\" alt=\"\" width=\"620\" height=\"327\" \/><\/p>\n<p>El valor de la representaci\u00f3n en los ensayos cl\u00ednicos<\/p>\n<p>Una representaci\u00f3n diversa en los ensayos cl\u00ednicos es fundamental para generar confianza entre los participantes y los investigadores. Cuando los participantes del estudio reflejan a la poblaci\u00f3n en general, es m\u00e1s probable que participen c\u00f3modamente en el proceso, lo que fomenta la confianza. Ampliar la diversidad en los ensayos cl\u00ednicos tambi\u00e9n nos ayuda a comprender c\u00f3mo los tratamientos afectan a los distintos grupos demogr\u00e1ficos, lo que mejora nuestro conocimiento del p\u00fablico objetivo de los diferentes medicamentos. Aceptar la diversidad conduce a resultados de investigaci\u00f3n m\u00e1s confiables y precisos, as\u00ed que asegur\u00e9monos de que todos tengan voz y voto.<\/p>","protected":false},"excerpt":{"rendered":"<p>Para celebrar el Mes Nacional de la Salud de las Minor\u00edas, analizamos el impacto de la diversidad en los ensayos cl\u00ednicos sobre la salud p\u00fablica. Los ensayos cl\u00ednicos desempe\u00f1an un papel crucial en la investigaci\u00f3n m\u00e9dica al probar la seguridad y eficacia de nuevos tratamientos, por lo que es esencial que reflejen con precisi\u00f3n la poblaci\u00f3n a la que pretenden servir. Siga leyendo para obtener m\u00e1s informaci\u00f3n... <\/p>\n<p class=\"read-more-container\"><a title=\"MES NACIONAL DE LA SALUD DE LAS MINOR\u00cdAS\" class=\"read-more button\" href=\"https:\/\/endeavorct.com\/es\/national-minority-health-month\/#more-1350\" aria-label=\"Leer m\u00e1s sobre MES NACIONAL DE LA SALUD DE LAS MINOR\u00cdAS\">Leer m\u00e1s<\/a><\/p>","protected":false},"author":17,"featured_media":1351,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,15],"tags":[63,61,80,81],"class_list":["post-1350","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clinical-research","category-clinical-trials","tag-clinical-research","tag-clinical-trials","tag-diversity","tag-minority","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NATIONAL MINORITY HEALTH MONTH - Endeavor Clinical Trials<\/title>\n<meta name=\"description\" content=\"In celebration of National Minority Health Month, we explore the impact of diversity in clinical trials on public health. Clinical trials play a crucial role in medical research by testing the safety and efficacy of new treatments, making it essential that they accurately reflect the population they aim to serve. Read on to learn more about this important topic.vvvvv\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/endeavorct.com\/es\/national-minority-health-month\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NATIONAL MINORITY HEALTH MONTH - Endeavor Clinical Trials\" \/>\n<meta property=\"og:description\" content=\"In celebration of National Minority Health Month, we explore the impact of diversity in clinical trials on public health. Clinical trials play a crucial role in medical research by testing the safety and efficacy of new treatments, making it essential that they accurately reflect the population they aim to serve. Read on to learn more about this important topic.vvvvv\" \/>\n<meta property=\"og:url\" content=\"https:\/\/endeavorct.com\/es\/national-minority-health-month\/\" \/>\n<meta property=\"og:site_name\" content=\"Endeavor Clinical Trials\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-17T19:16:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-21T20:16:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/endeavorct.com\/wp-content\/uploads\/2024\/04\/National-Minority-Health-Month.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1430\" \/>\n\t<meta property=\"og:image:height\" content=\"752\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jessica Seibel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jessica Seibel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/endeavorct.com\\\/national-minority-health-month\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/endeavorct.com\\\/national-minority-health-month\\\/\"},\"author\":{\"name\":\"Jessica Seibel\",\"@id\":\"https:\\\/\\\/endeavorct.com\\\/#\\\/schema\\\/person\\\/1cdb2152ebe811837293d55363c58076\"},\"headline\":\"NATIONAL MINORITY HEALTH MONTH\",\"datePublished\":\"2024-04-17T19:16:20+00:00\",\"dateModified\":\"2026-04-21T20:16:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/endeavorct.com\\\/national-minority-health-month\\\/\"},\"wordCount\":365,\"publisher\":{\"@id\":\"https:\\\/\\\/endeavorct.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/endeavorct.com\\\/national-minority-health-month\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/endeavorct.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/National-Minority-Health-Month.jpg\",\"keywords\":[\"Clinical Research\",\"Clinical trials\",\"Diversity\",\"Minority\"],\"articleSection\":[\"Clinical Research\",\"Clinical Trials\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/endeavorct.com\\\/national-minority-health-month\\\/\",\"url\":\"https:\\\/\\\/endeavorct.com\\\/national-minority-health-month\\\/\",\"name\":\"NATIONAL MINORITY HEALTH MONTH - Endeavor Clinical Trials\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/endeavorct.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/endeavorct.com\\\/national-minority-health-month\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/endeavorct.com\\\/national-minority-health-month\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/endeavorct.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/National-Minority-Health-Month.jpg\",\"datePublished\":\"2024-04-17T19:16:20+00:00\",\"dateModified\":\"2026-04-21T20:16:57+00:00\",\"description\":\"In celebration of National Minority Health Month, we explore the impact of diversity in clinical trials on public health. Clinical trials play a crucial role in medical research by testing the safety and efficacy of new treatments, making it essential that they accurately reflect the population they aim to serve. Read on to learn more about this important topic.vvvvv\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/endeavorct.com\\\/national-minority-health-month\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/endeavorct.com\\\/national-minority-health-month\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/endeavorct.com\\\/national-minority-health-month\\\/#primaryimage\",\"url\":\"https:\\\/\\\/endeavorct.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/National-Minority-Health-Month.jpg\",\"contentUrl\":\"https:\\\/\\\/endeavorct.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/National-Minority-Health-Month.jpg\",\"width\":1430,\"height\":752},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/endeavorct.com\\\/national-minority-health-month\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/endeavorct.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NATIONAL MINORITY HEALTH MONTH\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/endeavorct.com\\\/#website\",\"url\":\"https:\\\/\\\/endeavorct.com\\\/\",\"name\":\"Endeavor Clinical Trials\",\"description\":\"Clinical research in San Antonio, TX\",\"publisher\":{\"@id\":\"https:\\\/\\\/endeavorct.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/endeavorct.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/endeavorct.com\\\/#organization\",\"name\":\"Endeavor Clinical Trials\",\"url\":\"https:\\\/\\\/endeavorct.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/endeavorct.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/endeavorct.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/ECT-Blue-Logo-300x159-1-copy.webp\",\"contentUrl\":\"https:\\\/\\\/endeavorct.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/ECT-Blue-Logo-300x159-1-copy.webp\",\"width\":300,\"height\":159,\"caption\":\"Endeavor Clinical Trials\"},\"image\":{\"@id\":\"https:\\\/\\\/endeavorct.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/endeavorct.com\\\/#\\\/schema\\\/person\\\/1cdb2152ebe811837293d55363c58076\",\"name\":\"Jessica Seibel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/298f514f17125c57af40d1e2cfa6778ce4fe87541daa3f68eaa9847b5af19651?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/298f514f17125c57af40d1e2cfa6778ce4fe87541daa3f68eaa9847b5af19651?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/298f514f17125c57af40d1e2cfa6778ce4fe87541daa3f68eaa9847b5af19651?s=96&d=mm&r=g\",\"caption\":\"Jessica Seibel\"},\"url\":\"https:\\\/\\\/endeavorct.com\\\/es\\\/author\\\/jseibel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MES NACIONAL DE LA SALUD DE LAS MINOR\u00cdAS - Ensayos cl\u00ednicos Endeavor","description":"Para celebrar el Mes Nacional de la Salud de las Minor\u00edas, exploramos el impacto de la diversidad en los ensayos cl\u00ednicos en la salud p\u00fablica. Los ensayos cl\u00ednicos desempe\u00f1an un papel crucial en la investigaci\u00f3n m\u00e9dica, ya que eval\u00faan la seguridad y la eficacia de nuevos tratamientos, por lo que es fundamental que reflejen fielmente a la poblaci\u00f3n a la que se dirigen. Contin\u00fae leyendo para obtener m\u00e1s informaci\u00f3n sobre este importante tema.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/endeavorct.com\/es\/national-minority-health-month\/","og_locale":"es_MX","og_type":"article","og_title":"NATIONAL MINORITY HEALTH MONTH - Endeavor Clinical Trials","og_description":"In celebration of National Minority Health Month, we explore the impact of diversity in clinical trials on public health. Clinical trials play a crucial role in medical research by testing the safety and efficacy of new treatments, making it essential that they accurately reflect the population they aim to serve. Read on to learn more about this important topic.vvvvv","og_url":"https:\/\/endeavorct.com\/es\/national-minority-health-month\/","og_site_name":"Endeavor Clinical Trials","article_published_time":"2024-04-17T19:16:20+00:00","article_modified_time":"2026-04-21T20:16:57+00:00","og_image":[{"width":1430,"height":752,"url":"https:\/\/endeavorct.com\/wp-content\/uploads\/2024\/04\/National-Minority-Health-Month.jpg","type":"image\/jpeg"}],"author":"Jessica Seibel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jessica Seibel","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/endeavorct.com\/national-minority-health-month\/#article","isPartOf":{"@id":"https:\/\/endeavorct.com\/national-minority-health-month\/"},"author":{"name":"Jessica Seibel","@id":"https:\/\/endeavorct.com\/#\/schema\/person\/1cdb2152ebe811837293d55363c58076"},"headline":"NATIONAL MINORITY HEALTH MONTH","datePublished":"2024-04-17T19:16:20+00:00","dateModified":"2026-04-21T20:16:57+00:00","mainEntityOfPage":{"@id":"https:\/\/endeavorct.com\/national-minority-health-month\/"},"wordCount":365,"publisher":{"@id":"https:\/\/endeavorct.com\/#organization"},"image":{"@id":"https:\/\/endeavorct.com\/national-minority-health-month\/#primaryimage"},"thumbnailUrl":"https:\/\/endeavorct.com\/wp-content\/uploads\/2024\/04\/National-Minority-Health-Month.jpg","keywords":["Clinical Research","Clinical trials","Diversity","Minority"],"articleSection":["Clinical Research","Clinical Trials"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/endeavorct.com\/national-minority-health-month\/","url":"https:\/\/endeavorct.com\/national-minority-health-month\/","name":"MES NACIONAL DE LA SALUD DE LAS MINOR\u00cdAS - Ensayos cl\u00ednicos Endeavor","isPartOf":{"@id":"https:\/\/endeavorct.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/endeavorct.com\/national-minority-health-month\/#primaryimage"},"image":{"@id":"https:\/\/endeavorct.com\/national-minority-health-month\/#primaryimage"},"thumbnailUrl":"https:\/\/endeavorct.com\/wp-content\/uploads\/2024\/04\/National-Minority-Health-Month.jpg","datePublished":"2024-04-17T19:16:20+00:00","dateModified":"2026-04-21T20:16:57+00:00","description":"Para celebrar el Mes Nacional de la Salud de las Minor\u00edas, exploramos el impacto de la diversidad en los ensayos cl\u00ednicos en la salud p\u00fablica. Los ensayos cl\u00ednicos desempe\u00f1an un papel crucial en la investigaci\u00f3n m\u00e9dica, ya que eval\u00faan la seguridad y la eficacia de nuevos tratamientos, por lo que es fundamental que reflejen fielmente a la poblaci\u00f3n a la que se dirigen. Contin\u00fae leyendo para obtener m\u00e1s informaci\u00f3n sobre este importante tema.","breadcrumb":{"@id":"https:\/\/endeavorct.com\/national-minority-health-month\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/endeavorct.com\/national-minority-health-month\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/endeavorct.com\/national-minority-health-month\/#primaryimage","url":"https:\/\/endeavorct.com\/wp-content\/uploads\/2024\/04\/National-Minority-Health-Month.jpg","contentUrl":"https:\/\/endeavorct.com\/wp-content\/uploads\/2024\/04\/National-Minority-Health-Month.jpg","width":1430,"height":752},{"@type":"BreadcrumbList","@id":"https:\/\/endeavorct.com\/national-minority-health-month\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/endeavorct.com\/"},{"@type":"ListItem","position":2,"name":"NATIONAL MINORITY HEALTH MONTH"}]},{"@type":"WebSite","@id":"https:\/\/endeavorct.com\/#website","url":"https:\/\/endeavorct.com\/","name":"Ensayos cl\u00ednicos de esfuerzo","description":"Investigaci\u00f3n cl\u00ednica en San Antonio, TX","publisher":{"@id":"https:\/\/endeavorct.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/endeavorct.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/endeavorct.com\/#organization","name":"Ensayos cl\u00ednicos de esfuerzo","url":"https:\/\/endeavorct.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/endeavorct.com\/#\/schema\/logo\/image\/","url":"https:\/\/endeavorct.com\/wp-content\/uploads\/2026\/02\/ECT-Blue-Logo-300x159-1-copy.webp","contentUrl":"https:\/\/endeavorct.com\/wp-content\/uploads\/2026\/02\/ECT-Blue-Logo-300x159-1-copy.webp","width":300,"height":159,"caption":"Endeavor Clinical Trials"},"image":{"@id":"https:\/\/endeavorct.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/endeavorct.com\/#\/schema\/person\/1cdb2152ebe811837293d55363c58076","name":"Jessica Seibel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/298f514f17125c57af40d1e2cfa6778ce4fe87541daa3f68eaa9847b5af19651?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/298f514f17125c57af40d1e2cfa6778ce4fe87541daa3f68eaa9847b5af19651?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/298f514f17125c57af40d1e2cfa6778ce4fe87541daa3f68eaa9847b5af19651?s=96&d=mm&r=g","caption":"Jessica Seibel"},"url":"https:\/\/endeavorct.com\/es\/author\/jseibel\/"}]}},"_links":{"self":[{"href":"https:\/\/endeavorct.com\/es\/wp-json\/wp\/v2\/posts\/1350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/endeavorct.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/endeavorct.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/endeavorct.com\/es\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/endeavorct.com\/es\/wp-json\/wp\/v2\/comments?post=1350"}],"version-history":[{"count":0,"href":"https:\/\/endeavorct.com\/es\/wp-json\/wp\/v2\/posts\/1350\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/endeavorct.com\/es\/wp-json\/wp\/v2\/media\/1351"}],"wp:attachment":[{"href":"https:\/\/endeavorct.com\/es\/wp-json\/wp\/v2\/media?parent=1350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/endeavorct.com\/es\/wp-json\/wp\/v2\/categories?post=1350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/endeavorct.com\/es\/wp-json\/wp\/v2\/tags?post=1350"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}